{"id":4120,"date":"2023-10-03T15:39:45","date_gmt":"2023-10-03T13:39:45","guid":{"rendered":"https:\/\/www.cvs-avocats.com\/swipe-episode-5-cse-sur-mesure\/"},"modified":"2024-04-23T12:38:13","modified_gmt":"2024-04-23T10:38:13","slug":"swipe-episode-5-cse-sur-mesure","status":"publish","type":"post","link":"https:\/\/www.cvs-avocats.com\/fr\/swipe-episode-5-cse-sur-mesure\/","title":{"rendered":"[SWIPE] Episode 5\/5 : Se doter d\u2019un CSE sur mesure"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Vous allez prochainement organiser des\u00a0\u00e9lections\u00a0professionnelles afin de renouveler les\u00a0membres\u00a0de votre\u00a0CSE. A cette occasion, nous vous proposons cinq \u00e9pisodes pour vous pr\u00e9parer \u00e0 ce\u00a0renouvellement\u00a0et \u00e0 l\u2019optimisation\u00a0de son fonctionnement.<\/strong><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.cvs-avocats.com\/wp-content\/uploads\/2024\/04\/swipe-droit-social-renouveler-son-cse-cornet-vincent-sgurel-5-5-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Si le document ne s\u2019affiche pas, vous pouvez \u00e9galement t\u00e9l\u00e9charger le fichier PDF.\"><\/object><a id=\"wp-block-file--media-f7938f56-b22e-410c-9a79-6108c82febc6\" href=\"https:\/\/www.cvs-avocats.com\/wp-content\/uploads\/2024\/04\/swipe-droit-social-renouveler-son-cse-cornet-vincent-sgurel-5-5-1.pdf\">Si le document ne s\u2019affiche pas, vous pouvez \u00e9galement t\u00e9l\u00e9charger le fichier PDF<\/a><a href=\"https:\/\/www.cvs-avocats.com\/wp-content\/uploads\/2024\/04\/swipe-droit-social-renouveler-son-cse-cornet-vincent-sgurel-5-5-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f7938f56-b22e-410c-9a79-6108c82febc6\">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous allez prochainement organiser des\u00a0\u00e9lections\u00a0professionnelles afin de renouveler les\u00a0membres\u00a0de votre\u00a0CSE. A cette occasion, nous vous proposons cinq \u00e9pisodes pour vous pr\u00e9parer \u00e0 ce\u00a0renouvellement\u00a0et \u00e0 l\u2019optimisation\u00a0de son fonctionnement.<\/p>\n","protected":false},"author":7,"featured_media":4121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts\/4120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/comments?post=4120"}],"version-history":[{"count":0,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts\/4120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/media\/4121"}],"wp:attachment":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/media?parent=4120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/categories?post=4120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/tags?post=4120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}