{"id":2793,"date":"2020-01-17T09:49:41","date_gmt":"2020-01-17T08:49:41","guid":{"rendered":"https:\/\/www.cvs-avocats.com\/cotisations-at-mp\/"},"modified":"2020-01-17T09:49:41","modified_gmt":"2020-01-17T08:49:41","slug":"cotisations-at-mp","status":"publish","type":"post","link":"https:\/\/www.cvs-avocats.com\/fr\/cotisations-at-mp\/","title":{"rendered":"Cotisations AT-MP : disparition du taux bureau au 31 d\u00e9cembre 2019"},"content":{"rendered":"<div class=\"section__body\">\n<div class=\"block-strong-text\">\n<p><p>En application de l&rsquo;arr&ecirc;t&eacute; du 15 f&eacute;vrier 2017 (JO du 1er mars 2017), le taux de cotisations AT-MP &laquo; bureau &raquo; dispara&icirc;t au 31 d&eacute;cembre 2019. Ce dispositif permettait aux employeurs de b&eacute;n&eacute;ficier d&rsquo;une tarification r&eacute;duite pour certains de leurs salari&eacute;s non expos&eacute;s au risque principal de l&rsquo;entreprise.<\/p>\n<p>Depuis le 2 mars 2017, date d&rsquo;entr&eacute;e en vigueur de l&rsquo;arr&ecirc;t&eacute; susvis&eacute;, ce taux bureau a &eacute;t&eacute; remplac&eacute; par le taux &laquo; fonctions support de nature administrative &raquo;. La coexistence des deux dispositifs a n&eacute;anmoins &eacute;t&eacute; pr&eacute;vue jusqu&rsquo;au 31 d&eacute;cembre 2019.<\/p>\n<\/p><\/div>\n<article class=\"article-normal\">\n<div class=\"article__head\">\n<h2 class=\"article__title\">\n                    Le nouveaux taux fonctions support<br \/>\n                <\/h2>\n<\/p><\/div>\n<div class=\"article__entry\">\n<p>Alors que le b&eacute;n&eacute;fice du taux bureau &eacute;tait subordonn&eacute; au respect des deux conditions d&rsquo;ind&eacute;pendance du risque administratif et de s&eacute;dentarit&eacute; du personnel, trois crit&egrave;res doivent &ecirc;tre v&eacute;rifi&eacute;s pour l&rsquo;attribution du nouveau risque&nbsp;:<\/p>\n<h3>1. La taille de l&#039;entreprise<\/h3>\n<p>Le nouveau dispositif concerne les entreprises en taux collectif (moins de 20 salari&eacute;s) et mixte (de 20 &agrave; 149 salari&eacute;s). Les entreprises en tarification individuelle ne b&eacute;n&eacute;ficieront plus de cette tarification particuli&egrave;re pour le personnel des bureaux &agrave; compter du 1er janvier 2020.<\/p>\n<h3>2. Les fonctions exerc&eacute;es<\/h3>\n<p>Le nouveau dispositif ne concerne que les salari&eacute;s occupant &agrave; titre principal certaines fonctions support de nature administrative limitativement &eacute;num&eacute;r&eacute;es&nbsp;:<\/p>\n<ul>\n<li>le secr&eacute;tariat&nbsp;;<\/li>\n<li>l&rsquo;accueil&nbsp;;<\/li>\n<li>la comptabilit&eacute;&nbsp;;<\/li>\n<li>les affaires juridiques&nbsp;;<\/li>\n<li>la gestion financi&egrave;re&nbsp;;<\/li>\n<li>les ressources humaines.<\/li>\n<\/ul>\n<p>Ainsi, les employeurs ne pourront plus s&rsquo;en pr&eacute;valoir pour les salari&eacute;s exer&ccedil;ant des fonctions de direction, ou pour les salari&eacute;s des services informatique ou communication&#8230;<\/p>\n<p>La s&eacute;dentarit&eacute; des salari&eacute;s n&rsquo;est plus un crit&egrave;re.<\/p>\n<h3>3. Le crit&egrave;re d&#039;absence d&#039;exposition au risque<\/h3>\n<p>L&rsquo;administration pr&eacute;cise que l&rsquo;absence d&rsquo;exposition au risque concerne le local o&ugrave; travaille le salari&eacute;. Le local de travail n&rsquo;est pas expos&eacute; au risque s&rsquo;il est ferm&eacute;, m&ecirc;me s&rsquo;il se trouve au milieu de l&rsquo;atelier par exemple. Les conditions d&rsquo;acc&egrave;s du salari&eacute; audit local ne sont plus prises en compte (porte de communication ou travers&eacute;e d&rsquo;un parking, d&rsquo;un magasin&hellip;).<\/p>\n<\/p><\/div>\n<\/article>\n<article class=\"article-normal\">\n<div class=\"article__head\">\n<h2 class=\"article__title\">\n                    Le b\u00e9n\u00e9fice de ce dispositif est assujetti \u00e0 demande<br \/>\n                <\/h2>\n<\/p><\/div>\n<div class=\"article__entry\">\n<p><strong>L&rsquo;attribution du taux fonctions support n&rsquo;est pas automatique.<\/strong>&nbsp;L&rsquo;employeur en tarification collective ou mixte doit obligatoirement &eacute;mettre une demande aupr&egrave;s de la CARSAT, de la CRAMIF, ou de la CGSS dont il d&eacute;pend via un&nbsp;<a href=\"https:\/\/www.ameli.fr\/sites\/default\/files\/Documents\/535343\/document\/formulaire_dadhesion_taux_fonctions_supports_vdef_nov_19.pdf\" target=\"_blank\" rel=\"noopener\">formulaire d&eacute;di&eacute;<\/a>&nbsp;auquel il joindra la liste des salari&eacute;s &eacute;ligibles, l&rsquo;intitul&eacute; et la description de leur poste, ainsi qu&rsquo;un plan d&eacute;taill&eacute; de l&rsquo;implantation de l&rsquo;&eacute;tablissement.<\/p>\n<p><strong>Pour continuer &agrave; b&eacute;n&eacute;ficier d&rsquo;un taux r&eacute;duit, cette demande doit &ecirc;tre formul&eacute;e avant le 31 d&eacute;cembre 2019.&nbsp;<\/strong>A d&eacute;faut, le taux bureau sera supprim&eacute; au 1er janvier 2020.<\/p>\n<\/p><\/div>\n<\/article>\n<article class=\"article-normal\">\n<div class=\"article__head\">\n<h2 class=\"article__title\">\n                    Le taux collectif fix\u00e9 par arr\u00eat\u00e9 pour les fonctions support est de 0,9 % en 2019.<br \/>\n                <\/h2>\n<\/p><\/div>\n<div class=\"article__entry\"><\/div>\n<\/article>\n<article class=\"article-normal\">\n<div class=\"article__head\">\n<h2 class=\"article__title\">\n                    A compter du 1er janvier 2020<br \/>\n                <\/h2>\n<\/p><\/div>\n<div class=\"article__entry\">\n<p>A compter du 1er janvier 2020, pour les entreprises en taux individuel, et pour les entreprises en taux mixte n&rsquo;ayant pas formul&eacute; de demande avant le 31 d&eacute;cembre 2019, un seul taux sera appliqu&eacute;, calcul&eacute; en fusionnant le taux de l&rsquo;activit&eacute; principale avec celui du taux bureau. Selon l&rsquo;Administration, le nouveau taux issu de ce calcul devrait g&eacute;n&eacute;rer des cotisations&nbsp;<em>&laquo;&nbsp;sensiblement identiques&nbsp;&raquo;<\/em>&nbsp;&agrave; celles dues par application du dispositif pr&eacute;c&eacute;dent (application du taux de l&rsquo;activit&eacute; principale et du taux bureau).<\/p>\n<\/p><\/div>\n<\/article>\n<article class=\"article-normal\">\n<div class=\"article__head\">\n<h2 class=\"article__title\">\n                    Arr\u00eat\u00e9 du 21 d\u00e9cembre 2018<br \/>\n                <\/h2>\n<\/p><\/div>\n<div class=\"article__entry\">\n<p>Enfin, notez qu&rsquo;un arr&ecirc;t&eacute; du 21 d&eacute;cembre 2018 (JO du 23 d&eacute;cembre 2018) est venu compl&eacute;ter le dispositif en pr&eacute;voyant l&rsquo;application de r&egrave;gles d&rsquo;&eacute;cr&ecirc;tement dans le but de neutraliser, en partie, les risques de variation brutale de taux pour les entreprises en taux mixte ou individuel.<\/p>\n<\/p><\/div>\n<\/article><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En application de l&rsquo;arr&ecirc;t&eacute; du 15 f&eacute;vrier 2017 (JO du 1er mars 2017), le taux de cotisations AT-MP &laquo; bureau &raquo; dispara&icirc;t au 31 d&eacute;cembre 2019. Ce dispositif permettait aux employeurs de b&eacute;n&eacute;ficier d&rsquo;une tarification r&eacute;duite pour certains de leurs salari&eacute;s non expos&eacute;s au risque principal de l&rsquo;entreprise. Depuis le 2 mars 2017, date d&rsquo;entr&eacute;e [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":2794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts\/2793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/comments?post=2793"}],"version-history":[{"count":0,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/posts\/2793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/media\/2794"}],"wp:attachment":[{"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/media?parent=2793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/categories?post=2793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cvs-avocats.com\/fr\/wp-json\/wp\/v2\/tags?post=2793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}